{"id":60234,"date":"2024-03-08T16:09:04","date_gmt":"2024-03-08T15:09:04","guid":{"rendered":"https:\/\/www.pelletteriaveneta.com\/?post_type=product&#038;p=60234"},"modified":"2026-05-30T15:46:39","modified_gmt":"2026-05-30T13:46:39","slug":"borsa-a-mano-d24060-in-pelle-martellata","status":"publish","type":"product","link":"https:\/\/www.pelletteriaveneta.com\/it\/prodotto\/borsa-a-mano-d24060-in-pelle-martellata\/","title":{"rendered":"Borsa a mano D24060 in pelle martellata"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Borsa a mano in pelle<br \/>\n&#8211; con manico superiore rimovibile<br \/>\n&#8211; tracolla lunga inclusa<br \/>\n&#8211; patta superiore con fibbia di chiusura in metallo personalizzata<br \/>\n&#8211; tre scomparti a soffietto interni<br \/>\n&#8211; scomparto centrale con zip<br \/>\n&#8211; fodera in tessuto con tasche<br \/>\n&#8211; fondo rigido con piedini in metallo<br \/>\nMisura 38x29x16 cm.<br \/>\nFatta in Italia<\/p>\n","protected":false},"featured_media":62323,"template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[497,257],"product_tag":[],"class_list":["post-60234","product","type-product","status-publish","has-post-thumbnail","product_cat-borse-a-mano","product_cat-fine-serie","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Borsa a mano D24060 in pelle martellata - Pelletteria Veneta<\/title>\n<meta name=\"description\" content=\"Borsa a mano in pelle - con manico superiore rimovibile - tracolla lunga inclusa - patta superiore con fibbia di chiusura in metallo personalizzata - tre scomparti a soffietto interni - scomparto centrale con zip - fodera in tessuto con tasche - fondo rigido con piedini in metallo Misura 38x29x16 cm. Fatta in Italia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pelletteriaveneta.com\/it\/prodotto\/borsa-a-mano-d24060-in-pelle-martellata\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Borsa a mano D24060 in pelle martellata - Pelletteria Veneta\" \/>\n<meta property=\"og:description\" content=\"Borsa a mano in pelle - con manico superiore rimovibile - tracolla lunga inclusa - patta superiore con fibbia di chiusura in metallo personalizzata - tre scomparti a soffietto interni - scomparto centrale con zip - fodera in tessuto con tasche - fondo rigido con piedini in metallo Misura 38x29x16 cm. Fatta in Italia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pelletteriaveneta.com\/it\/prodotto\/borsa-a-mano-d24060-in-pelle-martellata\/\" \/>\n<meta property=\"og:site_name\" content=\"Pelletteria Veneta\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pelletteriavenetabags\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-30T13:46:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pelletteriaveneta.com\/wp-content\/uploads\/2024\/03\/D24060-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/it\\\/prodotto\\\/borsa-a-mano-d24060-in-pelle-martellata\\\/\",\"url\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/it\\\/prodotto\\\/borsa-a-mano-d24060-in-pelle-martellata\\\/\",\"name\":\"Borsa a mano D24060 in pelle martellata - Pelletteria Veneta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/it\\\/prodotto\\\/borsa-a-mano-d24060-in-pelle-martellata\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/it\\\/prodotto\\\/borsa-a-mano-d24060-in-pelle-martellata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/D24060-1-scaled.jpg\",\"datePublished\":\"2024-03-08T15:09:04+00:00\",\"dateModified\":\"2026-05-30T13:46:39+00:00\",\"description\":\"Borsa a mano in pelle - con manico superiore rimovibile - tracolla lunga inclusa - patta superiore con fibbia di chiusura in metallo personalizzata - tre scomparti a soffietto interni - scomparto centrale con zip - fodera in tessuto con tasche - fondo rigido con piedini in metallo Misura 38x29x16 cm. Fatta in Italia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/it\\\/prodotto\\\/borsa-a-mano-d24060-in-pelle-martellata\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pelletteriaveneta.com\\\/it\\\/prodotto\\\/borsa-a-mano-d24060-in-pelle-martellata\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/it\\\/prodotto\\\/borsa-a-mano-d24060-in-pelle-martellata\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/D24060-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/D24060-1-scaled.jpg\",\"width\":2560,\"height\":2560,\"caption\":\"Borsa a mano in pelle martellata con 3 scomparti separati e tracolla in tessuto\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/it\\\/prodotto\\\/borsa-a-mano-d24060-in-pelle-martellata\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/it\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Borse a mano\",\"item\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/it\\\/shop\\\/borse-a-mano\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Borsa a mano D24060 in pelle martellata\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/en\\\/\",\"name\":\"Pelletteria Veneta\",\"description\":\"Shop online di Pelletteria Veneta, borse in vera pelle Made in Italy\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/en\\\/#organization\",\"name\":\"Pelletteria Veneta\",\"url\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-Logo-Pelletteria-Veneta-2021-quadrato.jpg\",\"contentUrl\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-Logo-Pelletteria-Veneta-2021-quadrato.jpg\",\"width\":999,\"height\":999,\"caption\":\"Pelletteria Veneta\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pelletteriavenetabags\\\/\",\"https:\\\/\\\/www.instagram.com\\\/pelletteriaveneta\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Borsa a mano D24060 in pelle martellata - Pelletteria Veneta","description":"Borsa a mano in pelle - con manico superiore rimovibile - tracolla lunga inclusa - patta superiore con fibbia di chiusura in metallo personalizzata - tre scomparti a soffietto interni - scomparto centrale con zip - fodera in tessuto con tasche - fondo rigido con piedini in metallo Misura 38x29x16 cm. Fatta in Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pelletteriaveneta.com\/it\/prodotto\/borsa-a-mano-d24060-in-pelle-martellata\/","og_locale":"it_IT","og_type":"article","og_title":"Borsa a mano D24060 in pelle martellata - Pelletteria Veneta","og_description":"Borsa a mano in pelle - con manico superiore rimovibile - tracolla lunga inclusa - patta superiore con fibbia di chiusura in metallo personalizzata - tre scomparti a soffietto interni - scomparto centrale con zip - fodera in tessuto con tasche - fondo rigido con piedini in metallo Misura 38x29x16 cm. Fatta in Italia","og_url":"https:\/\/www.pelletteriaveneta.com\/it\/prodotto\/borsa-a-mano-d24060-in-pelle-martellata\/","og_site_name":"Pelletteria Veneta","article_publisher":"https:\/\/www.facebook.com\/pelletteriavenetabags\/","article_modified_time":"2026-05-30T13:46:39+00:00","og_image":[{"width":2560,"height":2560,"url":"https:\/\/www.pelletteriaveneta.com\/wp-content\/uploads\/2024\/03\/D24060-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pelletteriaveneta.com\/it\/prodotto\/borsa-a-mano-d24060-in-pelle-martellata\/","url":"https:\/\/www.pelletteriaveneta.com\/it\/prodotto\/borsa-a-mano-d24060-in-pelle-martellata\/","name":"Borsa a mano D24060 in pelle martellata - Pelletteria Veneta","isPartOf":{"@id":"https:\/\/www.pelletteriaveneta.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pelletteriaveneta.com\/it\/prodotto\/borsa-a-mano-d24060-in-pelle-martellata\/#primaryimage"},"image":{"@id":"https:\/\/www.pelletteriaveneta.com\/it\/prodotto\/borsa-a-mano-d24060-in-pelle-martellata\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pelletteriaveneta.com\/wp-content\/uploads\/2024\/03\/D24060-1-scaled.jpg","datePublished":"2024-03-08T15:09:04+00:00","dateModified":"2026-05-30T13:46:39+00:00","description":"Borsa a mano in pelle - con manico superiore rimovibile - tracolla lunga inclusa - patta superiore con fibbia di chiusura in metallo personalizzata - tre scomparti a soffietto interni - scomparto centrale con zip - fodera in tessuto con tasche - fondo rigido con piedini in metallo Misura 38x29x16 cm. Fatta in Italia","breadcrumb":{"@id":"https:\/\/www.pelletteriaveneta.com\/it\/prodotto\/borsa-a-mano-d24060-in-pelle-martellata\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pelletteriaveneta.com\/it\/prodotto\/borsa-a-mano-d24060-in-pelle-martellata\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.pelletteriaveneta.com\/it\/prodotto\/borsa-a-mano-d24060-in-pelle-martellata\/#primaryimage","url":"https:\/\/www.pelletteriaveneta.com\/wp-content\/uploads\/2024\/03\/D24060-1-scaled.jpg","contentUrl":"https:\/\/www.pelletteriaveneta.com\/wp-content\/uploads\/2024\/03\/D24060-1-scaled.jpg","width":2560,"height":2560,"caption":"Borsa a mano in pelle martellata con 3 scomparti separati e tracolla in tessuto"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pelletteriaveneta.com\/it\/prodotto\/borsa-a-mano-d24060-in-pelle-martellata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pelletteriaveneta.com\/it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.pelletteriaveneta.com\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Borse a mano","item":"https:\/\/www.pelletteriaveneta.com\/it\/shop\/borse-a-mano\/"},{"@type":"ListItem","position":4,"name":"Borsa a mano D24060 in pelle martellata"}]},{"@type":"WebSite","@id":"https:\/\/www.pelletteriaveneta.com\/en\/#website","url":"https:\/\/www.pelletteriaveneta.com\/en\/","name":"Pelletteria Veneta","description":"Shop online di Pelletteria Veneta, borse in vera pelle Made in Italy","publisher":{"@id":"https:\/\/www.pelletteriaveneta.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pelletteriaveneta.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.pelletteriaveneta.com\/en\/#organization","name":"Pelletteria Veneta","url":"https:\/\/www.pelletteriaveneta.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.pelletteriaveneta.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.pelletteriaveneta.com\/wp-content\/uploads\/2023\/05\/cropped-Logo-Pelletteria-Veneta-2021-quadrato.jpg","contentUrl":"https:\/\/www.pelletteriaveneta.com\/wp-content\/uploads\/2023\/05\/cropped-Logo-Pelletteria-Veneta-2021-quadrato.jpg","width":999,"height":999,"caption":"Pelletteria Veneta"},"image":{"@id":"https:\/\/www.pelletteriaveneta.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pelletteriavenetabags\/","https:\/\/www.instagram.com\/pelletteriaveneta\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.pelletteriaveneta.com\/it\/wp-json\/wp\/v2\/product\/60234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pelletteriaveneta.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.pelletteriaveneta.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pelletteriaveneta.com\/it\/wp-json\/wp\/v2\/media\/62323"}],"wp:attachment":[{"href":"https:\/\/www.pelletteriaveneta.com\/it\/wp-json\/wp\/v2\/media?parent=60234"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.pelletteriaveneta.com\/it\/wp-json\/wp\/v2\/product_brand?post=60234"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.pelletteriaveneta.com\/it\/wp-json\/wp\/v2\/product_cat?post=60234"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.pelletteriaveneta.com\/it\/wp-json\/wp\/v2\/product_tag?post=60234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}