{"id":51912,"date":"2023-11-17T16:45:03","date_gmt":"2023-11-17T14:45:03","guid":{"rendered":"https:\/\/www.pelletteriaveneta.com\/?post_type=product&#038;p=51912"},"modified":"2025-12-16T20:18:52","modified_gmt":"2025-12-16T19:18:52","slug":"borsa-a-mano-st23040-in-pelle-stampata-linea-betty-pelletteria-veneta","status":"publish","type":"product","link":"https:\/\/www.pelletteriaveneta.com\/it\/prodotto\/borsa-a-mano-st23040-in-pelle-stampata-linea-betty-pelletteria-veneta\/","title":{"rendered":"Borsa a mano ST23040 in pelle stampata Linea Betty Pelletteria Veneta"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Borsa a mano in pelle bycast<br \/>\n&#8211; design strutturato<br \/>\n&#8211; sacca rimovibile in microfibra<br \/>\n&#8211; doppi manici e tracolla<br \/>\nregolabile<br \/>\n&#8211; piedini in metallo<br \/>\nMisure: 37 x25,5 x15<br \/>\nPeso: 750 gr.<\/p>\n","protected":false},"featured_media":59268,"template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[497,257,37],"product_tag":[],"class_list":["post-51912","product","type-product","status-publish","has-post-thumbnail","product_cat-borse-a-mano","product_cat-fine-serie","product_cat-tracolle-in-pelle","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Borsa a mano ST23040 in pelle stampata Linea Betty Pelletteria Veneta - Pelletteria Veneta<\/title>\n<meta name=\"description\" content=\"Borsa a mano in pelle bycast - design strutturato - sacca rimovibile in microfibra - doppi manici e tracolla regolabile - piedini in metallo Misure: 37 x25,5 x15 Peso: 750 gr.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pelletteriaveneta.com\/it\/prodotto\/borsa-a-mano-st23040-in-pelle-stampata-linea-betty-pelletteria-veneta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Borsa a mano ST23040 in pelle stampata Linea Betty Pelletteria Veneta - Pelletteria Veneta\" \/>\n<meta property=\"og:description\" content=\"Borsa a mano in pelle bycast - design strutturato - sacca rimovibile in microfibra - doppi manici e tracolla regolabile - piedini in metallo Misure: 37 x25,5 x15 Peso: 750 gr.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pelletteriaveneta.com\/it\/prodotto\/borsa-a-mano-st23040-in-pelle-stampata-linea-betty-pelletteria-veneta\/\" \/>\n<meta property=\"og:site_name\" content=\"Pelletteria Veneta\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pelletteriavenetabags\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-16T19:18:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pelletteriaveneta.com\/wp-content\/uploads\/2023\/11\/ST23040-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/it\\\/prodotto\\\/borsa-a-mano-st23040-in-pelle-stampata-linea-betty-pelletteria-veneta\\\/\",\"url\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/it\\\/prodotto\\\/borsa-a-mano-st23040-in-pelle-stampata-linea-betty-pelletteria-veneta\\\/\",\"name\":\"Borsa a mano ST23040 in pelle stampata Linea Betty Pelletteria Veneta - Pelletteria Veneta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/it\\\/prodotto\\\/borsa-a-mano-st23040-in-pelle-stampata-linea-betty-pelletteria-veneta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/it\\\/prodotto\\\/borsa-a-mano-st23040-in-pelle-stampata-linea-betty-pelletteria-veneta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/ST23040-1.jpg\",\"datePublished\":\"2023-11-17T14:45:03+00:00\",\"dateModified\":\"2025-12-16T19:18:52+00:00\",\"description\":\"Borsa a mano in pelle bycast - design strutturato - sacca rimovibile in microfibra - doppi manici e tracolla regolabile - piedini in metallo Misure: 37 x25,5 x15 Peso: 750 gr.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/it\\\/prodotto\\\/borsa-a-mano-st23040-in-pelle-stampata-linea-betty-pelletteria-veneta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pelletteriaveneta.com\\\/it\\\/prodotto\\\/borsa-a-mano-st23040-in-pelle-stampata-linea-betty-pelletteria-veneta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/it\\\/prodotto\\\/borsa-a-mano-st23040-in-pelle-stampata-linea-betty-pelletteria-veneta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/ST23040-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/ST23040-1.jpg\",\"width\":1800,\"height\":1800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/it\\\/prodotto\\\/borsa-a-mano-st23040-in-pelle-stampata-linea-betty-pelletteria-veneta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/it\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Borse a mano\",\"item\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/it\\\/shop\\\/borse-a-mano\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Borsa a mano ST23040...\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/en\\\/\",\"name\":\"Pelletteria Veneta\",\"description\":\"Shop online di Pelletteria Veneta, borse in vera pelle Made in Italy\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/en\\\/#organization\",\"name\":\"Pelletteria Veneta\",\"url\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-Logo-Pelletteria-Veneta-2021-quadrato.jpg\",\"contentUrl\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-Logo-Pelletteria-Veneta-2021-quadrato.jpg\",\"width\":999,\"height\":999,\"caption\":\"Pelletteria Veneta\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pelletteriaveneta.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pelletteriavenetabags\\\/\",\"https:\\\/\\\/www.instagram.com\\\/pelletteriaveneta\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Borsa a mano ST23040 in pelle stampata Linea Betty Pelletteria Veneta - Pelletteria Veneta","description":"Borsa a mano in pelle bycast - design strutturato - sacca rimovibile in microfibra - doppi manici e tracolla regolabile - piedini in metallo Misure: 37 x25,5 x15 Peso: 750 gr.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pelletteriaveneta.com\/it\/prodotto\/borsa-a-mano-st23040-in-pelle-stampata-linea-betty-pelletteria-veneta\/","og_locale":"it_IT","og_type":"article","og_title":"Borsa a mano ST23040 in pelle stampata Linea Betty Pelletteria Veneta - Pelletteria Veneta","og_description":"Borsa a mano in pelle bycast - design strutturato - sacca rimovibile in microfibra - doppi manici e tracolla regolabile - piedini in metallo Misure: 37 x25,5 x15 Peso: 750 gr.","og_url":"https:\/\/www.pelletteriaveneta.com\/it\/prodotto\/borsa-a-mano-st23040-in-pelle-stampata-linea-betty-pelletteria-veneta\/","og_site_name":"Pelletteria Veneta","article_publisher":"https:\/\/www.facebook.com\/pelletteriavenetabags\/","article_modified_time":"2025-12-16T19:18:52+00:00","og_image":[{"width":1800,"height":1800,"url":"https:\/\/www.pelletteriaveneta.com\/wp-content\/uploads\/2023\/11\/ST23040-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pelletteriaveneta.com\/it\/prodotto\/borsa-a-mano-st23040-in-pelle-stampata-linea-betty-pelletteria-veneta\/","url":"https:\/\/www.pelletteriaveneta.com\/it\/prodotto\/borsa-a-mano-st23040-in-pelle-stampata-linea-betty-pelletteria-veneta\/","name":"Borsa a mano ST23040 in pelle stampata Linea Betty Pelletteria Veneta - Pelletteria Veneta","isPartOf":{"@id":"https:\/\/www.pelletteriaveneta.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pelletteriaveneta.com\/it\/prodotto\/borsa-a-mano-st23040-in-pelle-stampata-linea-betty-pelletteria-veneta\/#primaryimage"},"image":{"@id":"https:\/\/www.pelletteriaveneta.com\/it\/prodotto\/borsa-a-mano-st23040-in-pelle-stampata-linea-betty-pelletteria-veneta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pelletteriaveneta.com\/wp-content\/uploads\/2023\/11\/ST23040-1.jpg","datePublished":"2023-11-17T14:45:03+00:00","dateModified":"2025-12-16T19:18:52+00:00","description":"Borsa a mano in pelle bycast - design strutturato - sacca rimovibile in microfibra - doppi manici e tracolla regolabile - piedini in metallo Misure: 37 x25,5 x15 Peso: 750 gr.","breadcrumb":{"@id":"https:\/\/www.pelletteriaveneta.com\/it\/prodotto\/borsa-a-mano-st23040-in-pelle-stampata-linea-betty-pelletteria-veneta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pelletteriaveneta.com\/it\/prodotto\/borsa-a-mano-st23040-in-pelle-stampata-linea-betty-pelletteria-veneta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.pelletteriaveneta.com\/it\/prodotto\/borsa-a-mano-st23040-in-pelle-stampata-linea-betty-pelletteria-veneta\/#primaryimage","url":"https:\/\/www.pelletteriaveneta.com\/wp-content\/uploads\/2023\/11\/ST23040-1.jpg","contentUrl":"https:\/\/www.pelletteriaveneta.com\/wp-content\/uploads\/2023\/11\/ST23040-1.jpg","width":1800,"height":1800},{"@type":"BreadcrumbList","@id":"https:\/\/www.pelletteriaveneta.com\/it\/prodotto\/borsa-a-mano-st23040-in-pelle-stampata-linea-betty-pelletteria-veneta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pelletteriaveneta.com\/it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.pelletteriaveneta.com\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Borse a mano","item":"https:\/\/www.pelletteriaveneta.com\/it\/shop\/borse-a-mano\/"},{"@type":"ListItem","position":4,"name":"Borsa a mano ST23040..."}]},{"@type":"WebSite","@id":"https:\/\/www.pelletteriaveneta.com\/en\/#website","url":"https:\/\/www.pelletteriaveneta.com\/en\/","name":"Pelletteria Veneta","description":"Shop online di Pelletteria Veneta, borse in vera pelle Made in Italy","publisher":{"@id":"https:\/\/www.pelletteriaveneta.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pelletteriaveneta.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.pelletteriaveneta.com\/en\/#organization","name":"Pelletteria Veneta","url":"https:\/\/www.pelletteriaveneta.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.pelletteriaveneta.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.pelletteriaveneta.com\/wp-content\/uploads\/2023\/05\/cropped-Logo-Pelletteria-Veneta-2021-quadrato.jpg","contentUrl":"https:\/\/www.pelletteriaveneta.com\/wp-content\/uploads\/2023\/05\/cropped-Logo-Pelletteria-Veneta-2021-quadrato.jpg","width":999,"height":999,"caption":"Pelletteria Veneta"},"image":{"@id":"https:\/\/www.pelletteriaveneta.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pelletteriavenetabags\/","https:\/\/www.instagram.com\/pelletteriaveneta\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.pelletteriaveneta.com\/it\/wp-json\/wp\/v2\/product\/51912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pelletteriaveneta.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.pelletteriaveneta.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pelletteriaveneta.com\/it\/wp-json\/wp\/v2\/media\/59268"}],"wp:attachment":[{"href":"https:\/\/www.pelletteriaveneta.com\/it\/wp-json\/wp\/v2\/media?parent=51912"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.pelletteriaveneta.com\/it\/wp-json\/wp\/v2\/product_brand?post=51912"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.pelletteriaveneta.com\/it\/wp-json\/wp\/v2\/product_cat?post=51912"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.pelletteriaveneta.com\/it\/wp-json\/wp\/v2\/product_tag?post=51912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}